{"id":11333,"date":"2024-07-23T09:15:49","date_gmt":"2024-07-23T14:15:49","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=11333"},"modified":"2026-03-11T23:17:52","modified_gmt":"2026-03-12T04:17:52","slug":"quien-expide-las-normas-de-contabilidad-informacion-financiera-y-aseguramiento-en-colombia","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2024\/07\/quien-expide-las-normas-de-contabilidad-informacion-financiera-y-aseguramiento-en-colombia\/","title":{"rendered":"\u00bfQui\u00e9n expide las normas de contabilidad, informaci\u00f3n financiera y aseguramiento en Colombia?"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\"><em>Por: Kevin Guevara, asistente de investigaci\u00f3n t\u00e9cnica del INCP<\/em><\/p>\n\n\n\n<p><p style=\"text-align:justify\">En Colombia la convergencia hacia las normas internacionales de contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n comenz\u00f3 hace aproximadamente 15 a\u00f1os con la expedici\u00f3n de la Ley 1314 de 2009. Con esta ley, el pa\u00eds decidi\u00f3 conformar un sistema de informaci\u00f3n \u00fanico, homog\u00e9neo y de alta calidad, \u00fatil para apoyar la toma de decisiones econ\u00f3micas por parte de las diferentes partes interesadas.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align:justify\">El art\u00edculo 6 de la Ley 1314 de 2009 dispone que ser\u00e1n los ministerios de Hacienda y Cr\u00e9dito P\u00fablico (MinHacienda) y de Comercio, Industria y Turismo (MinCIT), obrando conjuntamente, los encargados de expedir los principios, normas, interpretaciones y gu\u00edas de contabilidad, informaci\u00f3n financiera y aseguramiento. Sin embargo, deber\u00e1 tener como base los proyectos presentados por el Consejo T\u00e9cnico de la Contadur\u00eda P\u00fablica (CTCP) en su calidad de organismo de normalizaci\u00f3n t\u00e9cnica. Por su parte, el art\u00edculo 10 de la misma ley dispone que las entidades estatales son quienes ejercen las funciones de supervisi\u00f3n (superintendencias), expedir normas t\u00e9cnicas especiales, realizar interpretaciones y gu\u00edas en materia de contabilidad, de informaci\u00f3n financiera y de aseguramiento de la informaci\u00f3n. Es de aclarar que estas actuaciones administrativas deber\u00e1n producirse dentro de los l\u00edmites fijados en la Constituci\u00f3n Pol\u00edtica de Colombia, la Ley 1314 de 2009 y las normas que la reglamenten y desarrollen.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Criterios que debe aplicar el CTCP<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align:justify\">En l\u00ednea con las disposiciones del art\u00edculo 8 de la Ley 1314 de 2009, el CTCP debe aplicar los siguientes criterios en la elaboraci\u00f3n de los proyectos que someta a consideraci\u00f3n del MinHacienda y del MinCIT:<\/p><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li style=\"text-align:justify; font-size:16px\">Asegurar que las propuestas se ajusten a las mejores pr\u00e1cticas internacionales utilizando procedimientos \u00e1giles, flexibles, transparentes y de p\u00fablico conocimiento.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Tener en cuenta la comparaci\u00f3n entre el beneficio y el costo que producir\u00edan sus proyectos en caso de ser convertidos en normas.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Tomar como referencia para la elaboraci\u00f3n de las propuestas, los est\u00e1ndares m\u00e1s recientes y de mayor aceptaci\u00f3n que hayan sido expedidos o est\u00e9n pr\u00f3ximos a ser expedidos por los organismos internacionales reconocidos a nivel mundial como emisores de est\u00e1ndares internacionales en el tema correspondiente, sus elementos y los fundamentos de sus conclusiones.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Comunicar las razones t\u00e9cnicas, al MinHacienda y al MinCIT, en el caso de que los referidos est\u00e1ndares internacionales, sus elementos o fundamentos no resulten eficaces o apropiados para los entes en Colombia.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Tener en cuenta las diferencias entre los entes econ\u00f3micos, tales como: tama\u00f1o, forma de organizaci\u00f3n jur\u00eddica, el sector al que pertenecen, n\u00famero de empleados e inter\u00e9s p\u00fablico involucrado en la actividad principal, para que los requisitos y obligaciones que se establezcan resulten razonables y acordes a tales circunstancias.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Propender por la participaci\u00f3n voluntaria de reconocidos expertos en los diferentes \u00e1mbitos de aplicaci\u00f3n de las normas.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Establecer comit\u00e9s t\u00e9cnicos <em>ad hon\u00f3rem<\/em> conformados por autoridades, preparadores, aseguradores y usuarios de la informaci\u00f3n financiera.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Considerar las recomendaciones que, fruto del an\u00e1lisis del impacto de los proyectos, sean formuladas por la Direcci\u00f3n de Impuestos y Aduanas Nacionales (DIAN), por los organismos responsables del dise\u00f1o y manejo de la pol\u00edtica econ\u00f3mica, por las entidades estatales que ejercen funciones de inspecci\u00f3n, vigilancia o control, y por quienes participen en los procesos de discusi\u00f3n p\u00fablica.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Disponer en medios divulgativos para discusi\u00f3n p\u00fablica los borradores de sus proyectos.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Publicar los proyectos definitivos una vez finalice su an\u00e1lisis y simult\u00e1neamente hacer la remisi\u00f3n al MinHacienda y al MinCIT.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Participar en los procesos de elaboraci\u00f3n de normas internacionales de contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n adelantados por instituciones internacionales, dentro de los l\u00edmites de sus recursos y de conformidad con las directrices establecidas por el Gobierno.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Evitar la duplicaci\u00f3n o repetici\u00f3n del trabajo realizado por otras instituciones con actividades de normalizaci\u00f3n internacional en estas materias.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Promover un proceso de divulgaci\u00f3n, conocimiento, comprensi\u00f3n y sensibilizaci\u00f3n de los procesos de convergencia de las normas con est\u00e1ndares internacionales en coordinaci\u00f3n con el Ministerio de Educaci\u00f3n (MinEducaci\u00f3n), MinHacienda, MinCIT y los representantes de las facultades y programas de contadur\u00eda p\u00fablica del pa\u00eds.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Criterios que deben aplicar los reguladores<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align:justify\">De acuerdo con el art\u00edculo 7 de la Ley 1314 de 2009, MinHacienda y MinCIT deben observar los siguientes criterios para la expedici\u00f3n de normas de contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n:<\/p><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li style=\"text-align:justify; font-size:16px\">Verificar que el proceso de elaboraci\u00f3n de los proyectos por parte del CTCP haya sido abierto, transparente y de p\u00fablico conocimiento.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Considerar las recomendaciones y observaciones que, como consecuencia del an\u00e1lisis del impacto de los proyectos, sean formuladas por la DIAN, por los organismos responsables del dise\u00f1o y manejo de la pol\u00edtica econ\u00f3mica y por las entidades estatales que ejercen funciones de inspecci\u00f3n, vigilancia o control.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Analizar y acoger, cuando resulte pertinente, las observaciones realizadas por el CTCP durante la etapa de exposici\u00f3n p\u00fablica de los proyectos con el an\u00e1lisis correspondiente.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Disponer la publicaci\u00f3n de las normas, junto con los fundamentos de sus conclusiones, en medios que garanticen su amplia divulgaci\u00f3n.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Revisar que las reglamentaciones sobre contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n sean consistentes, para lo cual velar\u00e1n porque las normas a expedir por otras autoridades de la rama ejecutiva resulten acordes con las disposiciones contenidas en la Ley de convergencia.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align:justify\">En conclusi\u00f3n, la expedici\u00f3n de normas de contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n en Colombia sigue un debido proceso establecido en la Ley 1314 de 2009. Esta ley asigna la responsabilidad a los organismos reguladores: ministerios de Hacienda y Cr\u00e9dito P\u00fablico y de Comercio, Industria y Turismo, quienes deben trabajar conjuntamente bas\u00e1ndose en los proyectos presentados por el CTCP como organismo normalizador.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><p style=\"text-align:justify\">Con base en lo anterior, es clave que los contadores p\u00fablicos y las diferentes partes interesadas de la profesi\u00f3n contable se involucren en las discusiones p\u00fablicas de los proyectos normativos que est\u00e1n considerados en el plan de trabajo del CTCP y de los organismos reguladores, entre otras cosas, porque de esta forma se facilita:<\/p><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li style=\"text-align:justify; font-size:16px\">La inclusi\u00f3n de diversas perspectivas: las partes interesadas aportan una variedad de puntos de vista y experiencias que enriquecen el proceso de discusi\u00f3n, asegurando que se consideren m\u00faltiples perspectivas y necesidades.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Legitimidad y aceptaci\u00f3n: la activa participaci\u00f3n de las partes interesadas genera un mayor respaldo y reconocimiento hacia las normas, facilitando su implementaci\u00f3n y cumplimiento efectivo.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Identificaci\u00f3n de impactos potenciales: las partes interesadas pueden se\u00f1alar posibles consecuencias no intencionadas o efectos adversos de las normas propuestas, permitiendo ajustes anticipados que mejoren su efectividad.<\/li>\n\n\n\n<li style=\"text-align:justify; font-size:16px\">Mejora continua: las contribuciones de las partes interesadas fomentan un proceso de mejora continua, donde las normas pueden adaptarse y evolucionar de manera m\u00e1s eficaz ante los cambios y desaf\u00edos emergentes.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>En Colombia la convergencia hacia las normas internacionales de contabilidad, informaci\u00f3n financiera y aseguramiento de la informaci\u00f3n comenz\u00f3 hace aproximadamente 15 a\u00f1os con la expedici\u00f3n de la Ley 1314 de 2009. Con esta ley, el pa\u00eds decidi\u00f3 conformar un sistema de informaci\u00f3n \u00fanico, homog\u00e9neo y de alta calidad, \u00fatil para apoyar la toma de decisiones econ\u00f3micas por parte de las diferentes partes interesadas.<\/p>\n","protected":false},"author":8,"featured_media":11325,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[544,5],"tags":[],"class_list":["post-11333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contabilidad-y-finanzas","category-contenidos"],"views":807,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=11333"}],"version-history":[{"count":11,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11333\/revisions"}],"predecessor-version":[{"id":14198,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11333\/revisions\/14198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/11325"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=11333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=11333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=11333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}