{"id":11458,"date":"2024-08-22T08:38:34","date_gmt":"2024-08-22T13:38:34","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=11458"},"modified":"2026-05-27T11:21:01","modified_gmt":"2026-05-27T16:21:01","slug":"metodos-de-valoracion-de-inventarios-bajo-niif","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2024\/08\/metodos-de-valoracion-de-inventarios-bajo-niif\/","title":{"rendered":"M\u00e9todos de valoraci\u00f3n de inventarios bajo NIIF"},"content":{"rendered":"\n<p><p style=\"text-align:justify\">En el marco de las Normas Internacionales de Informaci\u00f3n Financiera (NIIF), la Norma Internacional de Contabilidad (NIC) 2 &#8211; <em>Inventarios<\/em> establece el tratamiento contable de los inventarios mediante dos m\u00e9todos: PEPS y Promedio ponderado. Conoce m\u00e1s informaci\u00f3n de cada m\u00e9todo en nuestra infograf\u00eda.<\/p><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: <em>Kevin Guevara, asistente de investigaci\u00f3n t\u00e9cnica del INCP<\/em><\/p>\n\n\n<div class=\"_df_book df-lite\" id=\"df_14968\"  _slug=\"metodos-de-valoracion-de-inventarios-bajo-niif\" data-title=\"metodos-de-valoracion-de-inventarios-bajo-niif\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_14968 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"pageMode\":\"1\",\"source\":\"https:\\\/\\\/incp.org.co\\\/ContArte\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Metodos-de-valoracion-de-inventarios-bajo-NIIF-y-su-aplicacion-practica.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-34a2dbce-a53e-4527-affd-12e5ed4e2e93\" href=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2024\/08\/Metodos-de-valoracion-de-inventarios-bajo-NIIF-y-su-aplicacion-practica.pdf\" style=\"color:#00AEEF\">Descargar<\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>En el marco de las Normas Internacionales de Informaci\u00f3n Financiera (NIIF), la Norma Internacional de Contabilidad (NIC) 2 &#8211; Inventarios establece el tratamiento contable de los inventarios mediante dos m\u00e9todos: PEPS y Promedio ponderado. Conoce m\u00e1s informaci\u00f3n de cada m\u00e9todo en nuestra infograf\u00eda. Por: Kevin Guevara, asistente de investigaci\u00f3n t\u00e9cnica del INCP Descargar<\/p>\n","protected":false},"author":8,"featured_media":11450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,549],"tags":[],"class_list":["post-11458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contenidos","category-niif"],"views":882,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=11458"}],"version-history":[{"count":5,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11458\/revisions"}],"predecessor-version":[{"id":14970,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/11458\/revisions\/14970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/11450"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=11458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=11458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=11458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}