{"id":12714,"date":"2025-08-08T11:14:01","date_gmt":"2025-08-08T16:14:01","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=12714"},"modified":"2026-05-27T10:14:39","modified_gmt":"2026-05-27T15:14:39","slug":"que-son-las-alucinaciones-de-la-ia","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2025\/08\/que-son-las-alucinaciones-de-la-ia\/","title":{"rendered":"\u00bfQu\u00e9 son las alucinaciones de la IA?"},"content":{"rendered":"\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" rel=\"stylesheet\">\n<style> \n.container{\n  height: 200px;\n  position: relative;\n  border: 0px solid green;\n}\n\n.center{\n  margin: 0;\n  position: absolute;\n  top: 50%;\n  left: 35%;\n  -ms-transform: translate(-50%, -50%);\n  transform: translate(-50%, -50%);\n}\n.button {\n  background-color: #04AA6D;\n  border: none;\n  color: #04AA6D;;\n  padding: 16px 32px;\n  text-align: center;\n  text-decoration: none;\n  display: inline-block;\n  font-size: 16px;\n  margin: 4px 2px;\n  transition-duration: 0.4s;\n  cursor: pointer;\nborder-radius: 25px;\n}\n.button1 {\n  background-color: #04AA6D;\n  color: black; \n  border: 2px solid #04AA6D;\n}\n.button1:hover {\n  background-color: #04AA6D;;\n  color: white;\n}\n<\/style>\n<div class=\"container\">\n  <div class=\"center\">\n<a href=\"https:\/\/whatsapp.com\/channel\/0029Va8neTFCcW4h5pCJrM00\" target=\"_blank\" class=\"button button1\"> <i class=\"fa-brands fa-whatsapp\"><\/i>&nbsp;&nbsp;&nbsp;\u00danete a nuestro canal de whatsapp<\/a>\n <\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la inteligencia artificial (IA) da respuestas que suenan coherentes pero, en realidad, son err\u00f3neas o inventadas, se habla de una \u201calucinaci\u00f3n\u201d. Este fen\u00f3meno ocurre cuando un modelo de lenguaje de gran tama\u00f1o (LLM, por sus siglas en ingl\u00e9s) percibe patrones u objetos que no existen, de forma similar a c\u00f3mo los humanos vemos figuras en las nubes.<\/p>\n\n\n<div class=\"_df_book df-lite\" id=\"df_14913\"  _slug=\"que-son-las-alucinaciones-de-la-ia\" data-title=\"que-son-las-alucinaciones-de-la-ia\" wpoptions=\"true\" thumbtype=\"\" ><\/div><script class=\"df-shortcode-script\" nowprocket type=\"application\/javascript\">window.option_df_14913 = {\"outline\":[],\"autoEnableOutline\":\"false\",\"autoEnableThumbnail\":\"false\",\"overwritePDFOutline\":\"false\",\"direction\":\"1\",\"pageSize\":\"0\",\"pageMode\":\"1\",\"source\":\"https:\\\/\\\/incp.org.co\\\/ContArte\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Alucinaciones-de-IA-Post-de-Instagram-45.pdf\",\"wpOptions\":\"true\"}; if(window.DFLIP && window.DFLIP.parseBooks){window.DFLIP.parseBooks();}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Cuando la inteligencia artificial (IA) da respuestas que suenan coherentes pero, en realidad, son err\u00f3neas o inventadas, se habla de una \u201calucinaci\u00f3n\u201d. Este fen\u00f3meno ocurre cuando un modelo de lenguaje de gran tama\u00f1o (LLM, por sus siglas en ingl\u00e9s) percibe patrones u objetos que no existen, de forma similar a c\u00f3mo los humanos vemos figuras en las nubes.<\/p>\n","protected":false},"author":8,"featured_media":12721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,546],"tags":[],"class_list":["post-12714","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contenidos","category-tecnologia-e-innovacion"],"views":377,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/12714","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=12714"}],"version-history":[{"count":5,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/12714\/revisions"}],"predecessor-version":[{"id":14917,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/12714\/revisions\/14917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/12721"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=12714"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=12714"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=12714"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}