{"id":2334,"date":"2018-02-28T11:17:45","date_gmt":"2018-02-28T16:17:45","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=2334"},"modified":"2026-03-06T11:39:37","modified_gmt":"2026-03-06T16:39:37","slug":"estrategia-piedra-angular-de-la-gestion-empresarial","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2018\/02\/estrategia-piedra-angular-de-la-gestion-empresarial\/","title":{"rendered":"Estrategia: piedra angular de la gesti\u00f3n empresarial"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>La interiorizaci\u00f3n de la estrategia empresarial, como orientadora de los objetivos, pol\u00edticas y cursos de acci\u00f3n de la organizaci\u00f3n, <span style=\"color: #33cccc;\">debe estar presente en el proceder del contador p\u00fablico como participante clave<\/span> en la conducci\u00f3n y gesti\u00f3n de la compa\u00f1\u00eda.<\/em><!--more--><em>Por <span style=\"color: #00ccff;\">Johana Cano Hoyos<\/span>, asistente de investigaci\u00f3n del\u00a0<strong>INCP<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">Cualquier organizaci\u00f3n necesita desarrollar una estrategia para poder determinar sus objetivos, es decir, responder al \u201cqu\u00e9\u201d quiere lograr, y solo a partir de ella ser\u00e1 posible trazar el curso de acci\u00f3n y la correcta planeaci\u00f3n hacia los diferentes niveles corporativos. La estrategia, como piedra angular del direccionamiento corporativo, orienta las pol\u00edticas y decisiones operativas hacia las metas trazadas por la gerencia, reconociendo su contexto y entorno.<\/p>\n<p style=\"text-align: justify;\">Por tanto, debe ser un tema clave para los altos directivos \u2500entre ellos el contador p\u00fablico, como gerente financiero y administrativo\u2500 a fin de contribuir con el cumplimiento de los objetivos y de una gesti\u00f3n empresarial \u00f3ptima. Su utilidad radica en que permite determinar objetivos vitales y, una vez definidos, tener una idea m\u00e1s clara del lugar al que se desea llegar, c\u00f3mo conseguir\u00e1 hacerlo y cu\u00e1les ser\u00e1n las t\u00e1cticas necesarias.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan la Real Academia Espa\u00f1ola de la lengua \u2013 RAE, la estrategia es \u201cun proceso regulable, conjunto de las reglas que aseguran una decisi\u00f3n \u00f3ptima en cada momento\u201d. Esta definici\u00f3n se queda corta frente al desarrollo conceptual de la estrategia empresarial que a lo largo de varias d\u00e9cadas ha sido una labor de destacados empresarios y acad\u00e9micos de diversas disciplinas en el mundo.<\/p>\n<p style=\"text-align: justify;\">Dichos expertos, desde distintas \u00f3pticas, proporcionan definiciones, formas de concebirla, desarrollarla e implementarla a trav\u00e9s de publicaciones que van desde libros hasta art\u00edculos especializados, en donde se proponen teor\u00edas modelo, herramientas o t\u00e9cnicas \u00fatiles para los l\u00edderes organizacionales.<\/p>\n<p style=\"text-align: justify;\">Tal como se presenta en el art\u00edculo <em>La evoluci\u00f3n de la estrategia<\/em>, de <em>Harvard Deusto<\/em>, es innegable la considerable transformaci\u00f3n que ha tenido la estrategia, analizando con atenci\u00f3n aquellos modelos que se mantienen a\u00fan vigentes, comprobando sus beneficios para las empresas. Esta revisi\u00f3n tambi\u00e9n se\u00f1ala la importancia de remitirse al pasado, pues en muchas ocasiones, los nuevos postulados suponen un desarrollo de premisas previas que han servido como precursores de posiciones novedosas. A partir de este valioso documento se presentan los aportes m\u00e1s relevantes en esta materia en los \u00faltimos 50 a\u00f1os:<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2336\" src=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2018\/02\/La-estrategia_RCR-e1519834618528.jpg\" alt=\"\" width=\"700\" height=\"2100\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La interiorizaci\u00f3n de la estrategia empresarial, como orientadora de los objetivos, pol\u00edticas y cursos de acci\u00f3n de la organizaci\u00f3n, debe estar presente en el proceder del contador p\u00fablico como participante clave en la conducci\u00f3n y gesti\u00f3n de la compa\u00f1\u00eda.<\/p>\n","protected":false},"author":10,"featured_media":2335,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,548],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contenidos","category-organizacional"],"views":275,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/2334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":4,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":13326,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/2334\/revisions\/13326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}