{"id":6006,"date":"2020-10-06T14:41:25","date_gmt":"2020-10-06T19:41:25","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=6006"},"modified":"2026-03-06T14:06:10","modified_gmt":"2026-03-06T19:06:10","slug":"codigo-internacional-de-etica-para-profesionales-de-la-contabilidad","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2020\/10\/codigo-internacional-de-etica-para-profesionales-de-la-contabilidad\/","title":{"rendered":"C\u00f3digo Internacional de \u00c9tica para profesionales de la Contabilidad"},"content":{"rendered":"\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" rel=\"stylesheet\">\n\n<style> \n.container{\n  height: 200px;\n  width: 100%;\n  display: flex;\n  justify-content: center;\n  align-items: center;\n}\n\n.button,\n.button:link,\n.button:visited {\n  background-color: #04AA6D;\n  border: 2px solid #04AA6D;\n  color: black !important; \/* fuerza negro *\/\n  padding: 16px 32px;\n  text-align: center;\n  text-decoration: none;\n  display: inline-flex;\n  align-items: center;\n  font-size: 16px;\n  margin: 4px 2px;\n  transition: 0.4s;\n  cursor: pointer;\n  border-radius: 25px;\n}\n\n.button i {\n  color: black !important; \/* icono negro *\/\n}\n\n.button:hover {\n  background-color: #04AA6D;\n  color: white !important;\n}\n\n.button:hover i {\n  color: white !important;\n}\n<\/style>\n\n<div class=\"container\">\n  <a href=\"https:\/\/whatsapp.com\/channel\/0029Va8neTFCcW4h5pCJrM00\" target=\"_blank\" class=\"button\">\n    <i class=\"fa-brands fa-whatsapp\"><\/i>&nbsp;&nbsp;&nbsp;\u00danete a nuestro canal de whatsapp\n  <\/a>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Con todos los cambios que se han manifestado a nivel de modelo de negocio, de tecnolog\u00eda y el aumento de la vigilancia reglamentaria alrededor de la profesi\u00f3n contable en el contexto de crisis, ContArte retoma la \u00faltima versi\u00f3n del C\u00f3digo Internacional de \u00c9tica para profesionales de la Contabilidad con el fin de resaltar el papel que desempe\u00f1a la \u00e9tica actualmente, as\u00ed como su relevancia.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"1024\" data-id=\"6008\" src=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-01-410x1024.jpg\" alt=\"\" class=\"wp-image-6008\" srcset=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-01-410x1024.jpg 410w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-01-120x300.jpg 120w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-01.jpg 600w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"1024\" data-id=\"6009\" src=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-02-410x1024.jpg\" alt=\"\" class=\"wp-image-6009\" srcset=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-02-410x1024.jpg 410w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-02-120x300.jpg 120w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/c\u00f3digo-de-etica-02.jpg 600w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/figure>\n<\/figure>\n\n\n\n<div class=\"wp-block-file\"><a href=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/Codigo-Internacional-de-Etica-1.pdf\"><strong>Descargar PDF<\/strong><\/a><a href=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2020\/10\/Codigo-Internacional-de-Etica-1.pdf\" class=\"wp-block-file__button wp-element-button\" download>Descarga<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Con todos los cambios que se han manifestado a nivel de modelo de negocio, de tecnolog\u00eda y el aumento de la vigilancia reglamentaria alrededor de la profesi\u00f3n contable en el contexto de crisis, ContArte retoma la \u00faltima versi\u00f3n del C\u00f3digo Internacional de \u00c9tica para profesionales de la Contabilidad con el fin de resaltar el papel que desempe\u00f1a la \u00e9tica actualmente, as\u00ed como su relevancia.<\/p>\n","protected":false},"author":8,"featured_media":6012,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,501],"tags":[],"class_list":["post-6006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contenidos","category-etica"],"views":625,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=6006"}],"version-history":[{"count":2,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6006\/revisions"}],"predecessor-version":[{"id":13683,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6006\/revisions\/13683"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/6012"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=6006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=6006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=6006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}