{"id":6935,"date":"2021-03-24T18:11:14","date_gmt":"2021-03-24T23:11:14","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=6935"},"modified":"2026-03-11T12:29:44","modified_gmt":"2026-03-11T17:29:44","slug":"el-rol-de-los-contadores-en-la-agenda-2030-para-el-desarrollo-sostenible","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/investigacion\/2021\/03\/el-rol-de-los-contadores-en-la-agenda-2030-para-el-desarrollo-sostenible\/","title":{"rendered":"El rol de los contadores en la Agenda 2030 para el Desarrollo Sostenible"},"content":{"rendered":"\n<link href=\"https:\/\/cdnjs.cloudflare.com\/ajax\/libs\/font-awesome\/6.0.0-beta3\/css\/all.min.css\" rel=\"stylesheet\">\n\n<style> \n.container{\n  height: 200px;\n  width: 100%;\n  display: flex;\n  justify-content: center;\n  align-items: center;\n}\n\n.button,\n.button:link,\n.button:visited {\n  background-color: #04AA6D;\n  border: 2px solid #04AA6D;\n  color: black !important; \/* fuerza negro *\/\n  padding: 16px 32px;\n  text-align: center;\n  text-decoration: none;\n  display: inline-flex;\n  align-items: center;\n  font-size: 16px;\n  margin: 4px 2px;\n  transition: 0.4s;\n  cursor: pointer;\n  border-radius: 25px;\n}\n\n.button i {\n  color: black !important; \/* icono negro *\/\n}\n\n.button:hover {\n  background-color: #04AA6D;\n  color: white !important;\n}\n\n.button:hover i {\n  color: white !important;\n}\n<\/style>\n\n<div class=\"container\">\n  <a href=\"https:\/\/whatsapp.com\/channel\/0029Va8neTFCcW4h5pCJrM00\" target=\"_blank\" class=\"button\">\n    <i class=\"fa-brands fa-whatsapp\"><\/i>&nbsp;&nbsp;&nbsp;\u00danete a nuestro canal de whatsapp\n  <\/a>\n<\/div>\n\n\n\n<div class='embed-container'><iframe loading=\"lazy\" title=\"ContArte: El rol de los contadores en la Agenda 2030 para el Desarrollo Sostenible\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.youtube.com\/embed\/R-LB9rQZL0U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><br><em>Febrero 2021<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abstract:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los Objetivos de Desarrollo Sostenible empiezan a moldear los planes de desarrollo de gobiernos y los planes estrat\u00e9gicos de empresas. All\u00ed, los contadores, en l\u00ednea con el ODS 12.6, asumen el reto de ser quienes lideren la presentaci\u00f3n y elaboraci\u00f3n de reportes de sostenibilidad, mostrando generaci\u00f3n de valor m\u00e1s all\u00e1 de los temas netamente financieros. De esta manera, se presenta un camino para la evoluci\u00f3n de la profesi\u00f3n contable, tal y como sucedi\u00f3 en 2009 con la Ley 1314, en que el rol de los futuros contadores ser\u00e1 clave para responder a las tendencias y demandas del mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Art\u00edculo:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde su adopci\u00f3n en el a\u00f1o 2015, los 17 Objetivos de Desarrollo Sostenible (ODS) han marcado un camino claro para asegurar un planeta viable en el corto, mediano y largo plazo. Los objetivos propuestos son ambiciosos, por ende, han demandado la participaci\u00f3n de m\u00faltiples actores como gobiernos, entidades p\u00fablicas y privadas. Estos objetivos han moldeado la manera en que los gobiernos dise\u00f1an sus planes de desarrollo y las empresas, sus planes estrat\u00e9gicos, han impactado las din\u00e1micas de consumo de las personas, e incluso han repercutido en las preferencias de inversi\u00f3n en los mercados. Ahora, cabe preguntarnos, \u00bfc\u00f3mo han impactado en el presente y futuro de la profesi\u00f3n contable en el pa\u00eds? La respuesta no es clara, pero se pueden observar algunas tendencias; tal y como sucedi\u00f3 con la adopci\u00f3n de las NIIF en el a\u00f1o 2009, este ser\u00e1 un proceso de adaptaci\u00f3n y aprendizaje. Como contadores p\u00fablicos, con la Ley 1314 de 2009, empezamos a involucrarnos m\u00e1s en la toma de decisiones empresariales y en el monitoreo de la calidad de la informaci\u00f3n financiera en las organizaciones. Lo anterior enriqueci\u00f3 las \u00e1reas de participaci\u00f3n de la profesi\u00f3n contable y demand\u00f3 el desarrollo de nuevas habilidades, influyendo tambi\u00e9n en la formaci\u00f3n constante para los contadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algo parecido suceder\u00e1 a medida que las instituciones empiecen a adoptar pr\u00e1cticas sostenibles, motivadas por pol\u00edticas gubernamentales y por las tendencias de mercado. Espec\u00edficamente, dentro de los 17 ODS, el 12.6, que busca \u201cAlentar a las empresas, en especial las grandes empresas y las empresas transnacionales, a que adopten pr\u00e1cticas sostenibles e incorporen informaci\u00f3n sobre la sostenibilidad en su ciclo de presentaci\u00f3n de informes\u201d, presenta un reto para la elaboraci\u00f3n futura de los reportes financieros y de sostenibilidad. Esto demuestra la creciente conexi\u00f3n entre la informaci\u00f3n financiera y la no financiera, no solo para la toma de decisiones de corto plazo, sino aquellas que impacten el desarrollo de estrategias en el largo plazo. Hoy m\u00e1s que nunca, el valor de la informaci\u00f3n no financiera en una organizaci\u00f3n es un determinante para asegurar la permanencia de su negocio y, por ende, involucra a nuestra profesi\u00f3n para seguir creando, preservando y reportando valor en el mundo de negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All\u00ed, la profesi\u00f3n contable empieza a enfrentarse a un escenario cambiante, donde es fundamental el manejo contable y financiero desde una perspectiva que entienda la informaci\u00f3n en temas de sostenibilidad. Esto implica no solo el dominio de aspectos ASG (ambientales, sociales y de gobierno corporativo), sino el entendimiento del valor que estos aportan a las empresas y, por lo tanto, a la sociedad como conjunto. Para lograr esto, los retos estar\u00e1n en el desarrollo de nuevos procedimientos para el aseguramiento de la informaci\u00f3n no contable, la definici\u00f3n de prioridades dentro de las organizaciones, el establecimiento de objetivos en estas, la integraci\u00f3n de procesos para que la sostenibilidad est\u00e9 en el <em>core<\/em> de negocio y, finalmente, la aceptaci\u00f3n de est\u00e1ndares para el reporte de esta informaci\u00f3n. Tales esfuerzos garantizar\u00e1n unos m\u00ednimos de comparabilidad, verificabilidad, comprensi\u00f3n y pertinencia, en articulaci\u00f3n con otros actores o grupos de inter\u00e9s como los gobiernos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde nuestra posici\u00f3n de contadores en formaci\u00f3n, consideramos que es fundamental el acercamiento pr\u00e1ctico hacia estos temas desde una etapa temprana en la carrera, dando unas bases para afrontar las nuevas tendencias en la profesi\u00f3n. Como estudiantes de Contadur\u00eda Internacional en la Universidad de los Andes, realizamos una pr\u00e1ctica profesional en Ernst &amp; Young (EY) durante el primer semestre de 2020. All\u00ed, tuvimos la oportunidad de formar parte del equipo de trabajo de Felipe J\u00e1nica (socio l\u00edder de Financial Accounting Advisory Services (FAAS) en Latinoam\u00e9rica), para el desarrollo de un proyecto en cabeza de la Conferencia de las Naciones Unidas sobre Comercio y Desarrollo (UNCTAD). En el marco de la cooperaci\u00f3n internacional, Colombia fue uno de los pa\u00edses seleccionados para el acompa\u00f1amiento objeto del proyecto titulado <em>Habilitaci\u00f3n de marcos de pol\u00edticas para la sostenibilidad empresarial y la presentaci\u00f3n de informes sobre los ODS en \u00c1frica y Am\u00e9rica Latina<\/em>. El objetivo del proyecto era fortalecer las capacidades de los gobiernos para la medici\u00f3n y el monitoreo del sector privado en la Agenda 2030 para el Desarrollo Sostenible (ODS 12.6), en cuatro fases principales, bajo la asistencia de la UNCTAD.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro involucramiento se dio como parte del equipo consultor para el desarrollo de la tercera fase del proyecto, enfocada en mejorar la infraestructura de presentaci\u00f3n de informes de sostenibilidad de alta calidad. En este contexto, desarrollamos un plan de acci\u00f3n para la implementaci\u00f3n de estrategias que aportaran a la soluci\u00f3n de las problem\u00e1ticas identificadas en materia de reportes no financieros en Colombia. El resultado fue expuesto en un taller en el que participaron distintos ministerios, entidades p\u00fablicas y privadas, gremios y la academia. All\u00ed pudimos observar que, poco a poco, se incorporan los temas de sostenibilidad en la agenda de las grandes instituciones que moldean el futuro del pa\u00eds y las tendencias para los pr\u00f3ximos a\u00f1os. &nbsp;Adicionalmente, como futuros profesionales, entendimos que el camino para ganar experticia en temas de sostenibilidad es involucrarse, participar, proponer y cocrear en un entorno que relacione a la industria y la academia. Esperamos que, en un futuro cercano, esto marque un camino nuevo en la profesi\u00f3n contable y en el desarrollo de pol\u00edticas p\u00fablicas para la sostenibilidad en Colombia, pero sobretodo, hacemos un llamado a los profesionales contables para que adopten el cambio y den la oportunidad a que futuros contadores puedan tomar experiencias de este tipo y fortalecer sus conocimientos sobre las nuevas tendencias de la profesi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Actualmente, se vive una \u00e9poca definida por la cooperaci\u00f3n hacia un futuro m\u00e1s sostenible, presentando un escenario en el que los contadores podemos asumir el reto de estimular los impactos positivos y la confianza generada alrededor de la sostenibilidad. Insistimos en que no ser\u00e1 un cambio f\u00e1cil, pero la confianza puesta en generaciones futuras ser\u00e1 clave para que esta transici\u00f3n se d\u00e9 con mayor facilidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Autores:<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2-232x300.jpg\" alt=\"\" class=\"wp-image-6936\" srcset=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2-232x300.jpg 232w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2-791x1024.jpg 791w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2-768x994.jpg 768w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2-1187x1536.jpg 1187w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/JUAN-NICOLAS496-copy-2.jpg 1275w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Juan Nicol\u00e1s Casta\u00f1eda, estudiante de Contadur\u00eda Internacional y Administraci\u00f3n de Empresas en la Universidad de los Andes. Considero que el futuro de la profesi\u00f3n implica que, como contadores, tengamos la capacidad de tomar decisiones dentro de la empresa y de generar valor m\u00e1s all\u00e1 de los temas contables y financieros. Me apasionan las finanzas y el emprendimiento, por lo que hago parte del Club de Finanzas de la universidad en el \u00e1rea Fintech, donde encuentro un espacio para discutir temas de actualidad y aplicar de manera pr\u00e1ctica los conocimientos te\u00f3ricos adquiridos. Soy un convencido de que la relaci\u00f3n que tengamos con el medio ambiente puede determinar nuestro futuro. Hago lo que est\u00e1 en mis manos para hacer de Colombia un pa\u00eds cada d\u00eda mejor mediante mi profesi\u00f3n. Correo electr\u00f3nico: <a href=\"mailto:jn.castaneda@uniandes.edu.co\"><span class=\"has-inline-color has-vivid-cyan-blue-color\">jn.castaneda@uniandes.edu.co<\/span><\/a> \u2013 310 873 9418<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" src=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-1.30.33-PM-225x300.jpeg\" alt=\"\" class=\"wp-image-6938\" srcset=\"https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-1.30.33-PM-225x300.jpeg 225w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-1.30.33-PM-766x1024.jpeg 766w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-1.30.33-PM-768x1026.jpeg 768w, https:\/\/incp.org.co\/ContArte\/wp-content\/uploads\/2021\/03\/WhatsApp-Image-2021-03-17-at-1.30.33-PM.jpeg 958w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-left wp-block-paragraph\">Natalya Bossa, estudiante de Contadur\u00eda Internacional y Derecho en la Universidad de los Andes. La doble formaci\u00f3n profesional me ha permitido adquirir nuevas habilidades, as\u00ed como desarrollar m\u00e1s a profundidad aquellas obtenidas de mi formaci\u00f3n acad\u00e9mica como abogada. Adem\u00e1s del gusto por el aprendizaje y el conocimiento, tengo inter\u00e9s en aspectos art\u00edsticos y visuales. Considero que una formaci\u00f3n integral permite abordar situaciones de manera m\u00e1s creativa, desarrollar una mentalidad abierta y contar con herramientas diferenciadoras. Correo electr\u00f3nico: <a href=\"mailto:n.bossa@uniandes.edu.co\"><span class=\"has-inline-color has-vivid-cyan-blue-color\">n.bossa@uniandes.edu.co<\/span><\/a> \u2013 315 926 4417.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Objetivos de Desarrollo Sostenible empiezan a moldear los planes de desarrollo de gobiernos y los planes estrat\u00e9gicos de empresas. All\u00ed, los contadores, en l\u00ednea con el ODS 12.6, asumen el reto de ser quienes lideren la presentaci\u00f3n y elaboraci\u00f3n de reportes de sostenibilidad, mostrando generaci\u00f3n de valor m\u00e1s all\u00e1 de los temas netamente financieros. De esta manera, se presenta un camino para la evoluci\u00f3n de la profesi\u00f3n contable, tal y como sucedi\u00f3 en 2009 con la Ley 1314, en que el rol de los futuros contadores ser\u00e1 clave para responder a las tendencias y demandas del mercado.<\/p>\n","protected":false},"author":10,"featured_media":7000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,513],"tags":[],"class_list":["post-6935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-investigacion","category-sostenibilidad"],"views":1097,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=6935"}],"version-history":[{"count":10,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6935\/revisions"}],"predecessor-version":[{"id":14112,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/6935\/revisions\/14112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/7000"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=6935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=6935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=6935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}