{"id":8226,"date":"2022-03-01T13:16:21","date_gmt":"2022-03-01T18:16:21","guid":{"rendered":"https:\/\/incp.org.co\/ContArte\/?p=8226"},"modified":"2026-03-06T11:44:34","modified_gmt":"2026-03-06T16:44:34","slug":"dilemas-eticos-de-los-jovenes-contadores-de-la-teoria-a-la-practica","status":"publish","type":"post","link":"https:\/\/incp.org.co\/ContArte\/contenidos\/2022\/03\/dilemas-eticos-de-los-jovenes-contadores-de-la-teoria-a-la-practica\/","title":{"rendered":"Dilemas \u00e9ticos de los j\u00f3venes contadores: de la teor\u00eda a la pr\u00e1ctica"},"content":{"rendered":"\n<p class=\"has-text-align-left wp-block-paragraph\"><em>Uno de los mayores retos en la educaci\u00f3n de los futuros profesionales es conciliar la academia con la realidad profesional. \u00bfQu\u00e9 alternativas se est\u00e1n explorando?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por: <strong>Santiago Pedraza<\/strong>, asistente de investigaci\u00f3n t\u00e9cnica del <strong><span class=\"has-inline-color has-vivid-cyan-blue-color\">INCP<\/span><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A medida que los estudiantes de Contadur\u00eda P\u00fablica avanzan en su carrera, descubren la brecha existente entre la teor\u00eda y la pr\u00e1ctica. Son muchos los casos en los que, con base en supuestos, se plantean ejercicios en las aulas de clases para favorecer el desarrollo y entendimiento de los temas. Sin embargo, la realidad organizacional est\u00e1 a otro nivel. Llega a tener tal grado de complejidad, que desde la academia no se puede abordar satisfactoriamente. Solo cuando los j\u00f3venes contadores comienzan a vivir y a experimentar de primera mano el campo laboral, se dan cuenta que existen desaf\u00edos para los cuales no est\u00e1n preparados. Es as\u00ed, que m\u00e1s all\u00e1 de las normas, est\u00e1ndares y principios que son ense\u00f1ados, los futuros contadores requieren de un mayor acercamiento a esta realidad en la cual tendr\u00e1n que establecer relaciones con m\u00faltiples actores sociales, los cuales tienen sus intereses particulares y act\u00faan en conformidad con ellos. Se espera que el contador tenga la capacidad de evaluar las situaciones a las que se enfrenta y actuar en respuesta a dichas circunstancias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta evaluaci\u00f3n y an\u00e1lisis se vuelve dif\u00edcil bajo un enfoque basado en normas y reglas, con ausencia de interacci\u00f3n social: el comportamiento cambia cuando las personas se ven expuestas a una situaci\u00f3n concreta. El factor humano est\u00e1 presente en cada momento, no hay que olvidar el componente social de la informaci\u00f3n que suministra la contabilidad y los conflictos de inter\u00e9s que se presentan entre los agentes que interact\u00faan en las organizaciones. En este aspecto, es indudable la importancia de conocer los lineamientos en torno al buen actuar de la profesi\u00f3n, como lo es el <a href=\"https:\/\/incp.org.co\/Site\/publicaciones\/info\/archivos\/Restructured-code-ES.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">C\u00f3digo Internacional de \u00c9tica para Profesionales de la Contabilidad<\/a> con sus principios fundamentales (integridad, objetividad, competencia y debida diligencia, confidencialidad y conducta profesional). Sin embargo, para lograr interiorizar estos conceptos, se necesita que se complemente con el uso de un enfoque diferente, por ejemplo, el estudio de casos reales e imaginarios en los que se presenten los dilemas \u00e9ticos que pueden surgir, con ello se permite desarrollar un pensamiento cr\u00edtico y obtener un mejor juicio profesional. Desde la academia se tiene que ir avanzando en mejorar la forma de ense\u00f1ar \u00e9tica, es primordial que los j\u00f3venes estudiantes comprendan las dimensiones \u00e9ticas detr\u00e1s de los aprendizajes t\u00e9cnicos, con la finalidad de que est\u00e9n mejor preparados para enfrentar los dilemas \u00e9ticos que encuentren en la pr\u00e1ctica contable. Falta abordar m\u00e1s problemas comunes al ejercicio profesional, que se den espacios de discusi\u00f3n en los que se reflexione sobre lo que significa ser un contador \u00e9tico. Tambi\u00e9n resulta interesante plantear m\u00e9todos de aprendizaje en grupo, con juegos de roles o debates en grupos peque\u00f1os que favorezcan el trabajo colaborativo. Con ello se contribuir\u00e1 al fortalecimiento del componente \u00e9tico de los futuros contadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este trabajo ya ha sido emprendido desde el Consejo de Normas Internacionales de \u00c9tica para Contadores (IESBA, por sus siglas en ingl\u00e9s), quienes d\u00eda a d\u00eda mejoran el C\u00f3digo Internacional de \u00c9tica para Contadores para abarcar en profundidad todas las dimensiones \u00e9ticas a las que se enfrentan los contadores. Los esfuerzos del IESBA est\u00e1n enfocados en realizar mejoras significativas al C\u00f3digo para abordar de forma m\u00e1s completa y clara la aplicaci\u00f3n de los principios \u00e9ticos en un mundo tan cambiante como el actual. Recordemos que el C\u00f3digo Internacional de \u00c9tica para Contadores fue incluido en la normatividad de la profesi\u00f3n contable colombiana desde la llegada de la Ley 1314 de 2009. En la actualidad, resulta imperativo poner en el centro de atenci\u00f3n estos temas ya que el actuar profesional de los contadores debe propender por el inter\u00e9s p\u00fablico y la ciencia contable es sin duda una ciencia social. Hay mucho por mejorar, ser\u00e1 fundamental generar ideas novedosas de c\u00f3mo formar a un contador \u00e9tico y evaluar de forma integral el contenido y la pedagog\u00eda impartida por las instituciones educativas con el \u00e1nimo de que se formen j\u00f3venes contadores capaces de resolver de la forma m\u00e1s acertada cualquier dilema \u00e9tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los mayores retos en la educaci\u00f3n de los futuros profesionales es conciliar la academia con la realidad profesional. \u00bfQu\u00e9 alternativas se est\u00e1n explorando? Por: Santiago Pedraza, asistente de investigaci\u00f3n t\u00e9cnica del INCP A medida que los estudiantes de Contadur\u00eda P\u00fablica avanzan en su carrera, descubren la brecha existente entre la teor\u00eda y la&hellip; <br \/> <a class=\"read-more\" href=\"https:\/\/incp.org.co\/ContArte\/contenidos\/2022\/03\/dilemas-eticos-de-los-jovenes-contadores-de-la-teoria-a-la-practica\/\">Read more<\/a><\/p>\n","protected":false},"author":8,"featured_media":8227,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,501],"tags":[],"class_list":["post-8226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contenidos","category-etica"],"views":1927,"_links":{"self":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/8226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/comments?post=8226"}],"version-history":[{"count":4,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/8226\/revisions"}],"predecessor-version":[{"id":13993,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/posts\/8226\/revisions\/13993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media\/8227"}],"wp:attachment":[{"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/media?parent=8226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/categories?post=8226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/incp.org.co\/ContArte\/wp-json\/wp\/v2\/tags?post=8226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}